{"id":35,"date":"2023-04-03T20:52:42","date_gmt":"2023-04-03T18:52:42","guid":{"rendered":"https:\/\/istitutobuenosaires.esteri.it\/?page_id=35"},"modified":"2024-07-19T19:21:37","modified_gmt":"2024-07-19T10:21:37","slug":"calendario","status":"publish","type":"page","link":"https:\/\/iictokyo.esteri.it\/it\/gli_eventi\/calendario\/","title":{"rendered":"Eventi in programma"},"content":{"rendered":"        <div class=\"row\">\n\t\t\t<!-- Ricerca sedi post -->\n\t\t\t<div class=\"col-12 mt-4\">\n\t\t\t  <div class=\"callout callout-highlight note ricerca-esteri p-4\">\n                    <div class=\"callout-title\">\n                        <svg class=\"icon\">\n                            <use xlink:href=\"https:\/\/iictokyo.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-search\"><\/use>\n                        <\/svg>Inserisci i parametri di ricerca                    <\/div>\n                    <form id=\"searchFormPost\" name=\"form-search-post\" class=\"form-row align-items-center\" action=\"https:\/\/iictokyo.esteri.it\/it\/wp-json\/wp\/v2\/pages\/35\/\" method=\"GET\"> \n                        <!-- <div class=\"form-group pt-5\"> -->\n                            <!-- <input type=\"hidden\" id=\"lang\" name=\"lang\" value=\"\"> --> <!-- <\/div> -->\n\n                        <div class=\"it-datepicker-wrapper\">\n                            <div class=\"row\">\n                                <div class=\"form-group col-md-6\">\n                                    <label class=\"active\" for=\"date-init\">Dal<\/label>\n                                    <input class=\"form-control\" name=\"date-init\" id=\"date-init\" type=\"date\" placeholder=\"gg\/mm\/aaaa\" value=\"\"lang=\"en-EN\">  \n                                <\/div>\n                                <div class=\"form-group col-md-6\">\n                                    <label class=\"active\" for=\"date-end\">Al<\/label>\n                                    <input class=\"form-control\" name=\"date-end\" id=\"date-end\" type=\"date\" placeholder=\"gg\/mm\/aaaa\" value=\"\">\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                        <div class=\"form-group col-md-12 mt-3\">\n                            <label for=\"searchText\">Campo ricerca libera<\/label>\n                            <input type=\"text\" name=\"searchText\" class=\"form-control\" id=\"searchText\" value=\"\">\n                        <\/div>\n                        <div class=\"form-group col-md-4 offset-md-8 text-end\">\n                            <a href=\"https:\/\/iictokyo.esteri.it\/it\/gli_eventi\/calendario\/\" title=\"Form reset\" id=\"resetImput\" class=\"btn btn-outline-primary btn-xs\">Reset<\/a>\n                            <button type=\"submit\" class=\"btn btn-primary btn-xs\">Mostra risultati<\/button>\n                        <\/div>\n                    <\/form>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n                    \n            <div class=\"row\">\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body row\">\n                                                    <div class=\"col-sm-3\">\n                                <div class=\"img-responsive\">\n                                    <figure class=\"img-wrapper\">\n                                        <a href=\"https:\/\/iictokyo.esteri.it\/it\/gli_eventi\/calendario\/turandot-delle-stelle\/\" title=\"Leggi l'articolo: Turandot delle stelle\">\n                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"139\" src=\"https:\/\/iictokyo.esteri.it\/wp-content\/uploads\/2026\/07\/TURANDOT-DELLE-STELLE-6-300x139.jpg\" srcset=\"https:\/\/iictokyo.esteri.it\/wp-content\/uploads\/2026\/07\/TURANDOT-DELLE-STELLE-6.jpg 1697w, https:\/\/iictokyo.esteri.it\/wp-content\/uploads\/2026\/07\/TURANDOT-DELLE-STELLE-6-300x139.jpg 300w, https:\/\/iictokyo.esteri.it\/wp-content\/uploads\/2026\/07\/TURANDOT-DELLE-STELLE-6-1024x474.jpg 1024w, https:\/\/iictokyo.esteri.it\/wp-content\/uploads\/2026\/07\/TURANDOT-DELLE-STELLE-6-768x355.jpg 768w\" sizes=\"auto, (max-width: 1697px) 100vw, 1697px\"  title=\"TURANDOT DELLE STELLE 6\" alt=\"\" class=\"img-fluid\">\n                                                                                    <\/a>\n                                    <\/figure>\n                                <\/div>\n                            <\/div>\n                            <div class=\"col-sm-9\">\n                                                            <div class=\"category-top\">\n                                    <span class=\"fw-bold \"><\/span>                                                                        <span class=\"\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/iictokyo.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> Gio 03 Set 2026<svg class=\"icon icon-xs icon-secondary me-1 ms-1\"><use href=\"https:\/\/iictokyo.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use><\/svg>Gio 03 Set 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/iictokyo.esteri.it\/it\/gli_eventi\/calendario\/turandot-delle-stelle\/\" title=\"Turandot delle stelle\">Turandot delle stelle<\/a><\/h5>\n                            <p class=\"card-text\">Turandot delle Stelle \u00e8 una performance immersiva di video mapping e musica dal vivo, ideata e diretta da Davide Giannoni e Francesca Pasquinucci (Imaginarium Creative Studio), creata per celebrare il centenario della prima rappresentazione di Turandot, avvenuta al Teatro alla Scala il 25 aprile 1926. Lo spettacolo fonde il capolavoro incompiuto di Puccini con musica [&hellip;]<\/p>\n                                <a title=\"Turandot delle stelle\" class=\"read-more\" href=\"https:\/\/iictokyo.esteri.it\/it\/gli_eventi\/calendario\/turandot-delle-stelle\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/iictokyo.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                        <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body row\">\n                                                    <div class=\"col-sm-3\">\n                                <div class=\"img-responsive\">\n                                    <figure class=\"img-wrapper\">\n                                        <a href=\"https:\/\/iictokyo.esteri.it\/it\/gli_eventi\/calendario\/chiyoda-international-exchange-fair-2026\/\" title=\"Leggi l'articolo: Chiyoda International Exchange Fair 2026\">\n                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/iictokyo.esteri.it\/wp-content\/uploads\/2026\/08\/a1a58b1f2bd53670ce431c60094a9450019712ac-300x200.png\" srcset=\"https:\/\/iictokyo.esteri.it\/wp-content\/uploads\/2026\/08\/a1a58b1f2bd53670ce431c60094a9450019712ac.png 360w, https:\/\/iictokyo.esteri.it\/wp-content\/uploads\/2026\/08\/a1a58b1f2bd53670ce431c60094a9450019712ac-300x200.png 300w\" sizes=\"auto, (max-width: 360px) 100vw, 360px\"  title=\"a1a58b1f2bd53670ce431c60094a9450019712ac\" alt=\"\" class=\"img-fluid\">\n                                                                                    <\/a>\n                                    <\/figure>\n                                <\/div>\n                            <\/div>\n                            <div class=\"col-sm-9\">\n                                                            <div class=\"category-top\">\n                                    <span class=\"fw-bold \"><\/span>                                                                        <span class=\"\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/iictokyo.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> Sab 05 Set 2026<svg class=\"icon icon-xs icon-secondary me-1 ms-1\"><use href=\"https:\/\/iictokyo.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use><\/svg>Sab 05 Set 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/iictokyo.esteri.it\/it\/gli_eventi\/calendario\/chiyoda-international-exchange-fair-2026\/\" title=\"Chiyoda International Exchange Fair 2026\">Chiyoda International Exchange Fair 2026<\/a><\/h5>\n                            <p class=\"card-text\">La Chiyoda International Exchange Fair \u00e8 un evento per la promozione degli scambi internazionali organizzato dal comune di Chiyoda in collaborazione con le ambasciate e le istituzioni culturali presenti nel comune. Anche in questa edizione saranno presenti numerosi stand, workshop e performance artistiche, che offriranno la possibilit\u00e0 di scoprire la cultura e l\u2019arte dei vari [&hellip;]<\/p>\n                                <a title=\"Chiyoda International Exchange Fair 2026\" class=\"read-more\" href=\"https:\/\/iictokyo.esteri.it\/it\/gli_eventi\/calendario\/chiyoda-international-exchange-fair-2026\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/iictokyo.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                        <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body row\">\n                                                    <div class=\"col-sm-3\">\n                                <div class=\"img-responsive\">\n                                    <figure class=\"img-wrapper\">\n                                        <a href=\"https:\/\/iictokyo.esteri.it\/it\/gli_eventi\/calendario\/pitecus-spettacolo-di-flavia-mastrella-e-antonio-rezza-con-antonio-rezza\/\" title=\"Leggi l'articolo: Pitecus \u2013 Spettacolo di Flavia Mastrella e Antonio Rezza, con Antonio Rezza\">\n                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/iictokyo.esteri.it\/wp-content\/uploads\/2026\/07\/20260908_Pitecus_Foto-per_sito-300x200.jpg\" srcset=\"https:\/\/iictokyo.esteri.it\/wp-content\/uploads\/2026\/07\/20260908_Pitecus_Foto-per_sito.jpg 1275w, https:\/\/iictokyo.esteri.it\/wp-content\/uploads\/2026\/07\/20260908_Pitecus_Foto-per_sito-300x200.jpg 300w, https:\/\/iictokyo.esteri.it\/wp-content\/uploads\/2026\/07\/20260908_Pitecus_Foto-per_sito-1024x683.jpg 1024w, https:\/\/iictokyo.esteri.it\/wp-content\/uploads\/2026\/07\/20260908_Pitecus_Foto-per_sito-768x512.jpg 768w\" sizes=\"auto, (max-width: 1275px) 100vw, 1275px\"  title=\"20260908_Pitecus_Foto-per_sito\" alt=\"\" class=\"img-fluid\">\n                                                                                    <\/a>\n                                    <\/figure>\n                                <\/div>\n                            <\/div>\n                            <div class=\"col-sm-9\">\n                                                            <div class=\"category-top\">\n                                    <span class=\"fw-bold \"><\/span>                                                                        <span class=\"\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/iictokyo.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> Mar 08 Set 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/iictokyo.esteri.it\/it\/gli_eventi\/calendario\/pitecus-spettacolo-di-flavia-mastrella-e-antonio-rezza-con-antonio-rezza\/\" title=\"Pitecus \u2013 Spettacolo di Flavia Mastrella e Antonio Rezza, con Antonio Rezza\">Pitecus \u2013 Spettacolo di Flavia Mastrella e Antonio Rezza, con Antonio Rezza<\/a><\/h5>\n                            <p class=\"card-text\">\u00a0Uomini e donne caratterizzati dalle proprie ossessioni si alternano sul palco e prendono vita grazie alla voce e ai gesti di Antonio Rezza. Il loro volti e frammenti del loro corpo si affacciano di volta in volta dalle architetture in stoffa create da Flavia Mastrella, dando vita e voce al loro egoismo, a desideri frustrati [&hellip;]<\/p>\n                                <a title=\"Pitecus \u2013 Spettacolo di Flavia Mastrella e Antonio Rezza, con Antonio Rezza\" class=\"read-more\" href=\"https:\/\/iictokyo.esteri.it\/it\/gli_eventi\/calendario\/pitecus-spettacolo-di-flavia-mastrella-e-antonio-rezza-con-antonio-rezza\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/iictokyo.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                        <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body row\">\n                                                    <div class=\"col-sm-3\">\n                                <div class=\"img-responsive\">\n                                    <figure class=\"img-wrapper\">\n                                        <a href=\"https:\/\/iictokyo.esteri.it\/it\/gli_eventi\/calendario\/identita-oltre-confine-dialogo-tra-essere-umano-e-natura-nelle-opere-della-collezione-farnesina\/\" title=\"Leggi l'articolo: Identit\u00e0 oltre confine. Dialogo tra essere umano e natura nelle opere della Collezione Farnesina\">\n                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/iictokyo.esteri.it\/wp-content\/uploads\/2026\/08\/Mariagrazia_Pontorno_per_sito-300x169.jpg\" srcset=\"https:\/\/iictokyo.esteri.it\/wp-content\/uploads\/2026\/08\/Mariagrazia_Pontorno_per_sito.jpg 1511w, https:\/\/iictokyo.esteri.it\/wp-content\/uploads\/2026\/08\/Mariagrazia_Pontorno_per_sito-300x169.jpg 300w, https:\/\/iictokyo.esteri.it\/wp-content\/uploads\/2026\/08\/Mariagrazia_Pontorno_per_sito-1024x576.jpg 1024w, https:\/\/iictokyo.esteri.it\/wp-content\/uploads\/2026\/08\/Mariagrazia_Pontorno_per_sito-768x432.jpg 768w\" sizes=\"auto, (max-width: 1511px) 100vw, 1511px\"  title=\"Mariagrazia_Pontorno_per_sito\" alt=\"\u30de\u30ea\u30a2\u30b0\u30e9\u30c4\u30a3\u30a2\u30fb\u30dd\u30f3\u30c8\u30eb\u30ce \u300a\u5929\u7a7a\u306e\u30ec\u30d0\u30ce\u30f3\u6749\u300b\" class=\"img-fluid\">\n                                                                                    <\/a>\n                                    <\/figure>\n                                <\/div>\n                            <\/div>\n                            <div class=\"col-sm-9\">\n                                                            <div class=\"category-top\">\n                                    <span class=\"fw-bold \"><\/span>                                                                        <span class=\"\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/iictokyo.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> Sab 12 Set 2026<svg class=\"icon icon-xs icon-secondary me-1 ms-1\"><use href=\"https:\/\/iictokyo.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use><\/svg>Gio 22 Ott 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/iictokyo.esteri.it\/it\/gli_eventi\/calendario\/identita-oltre-confine-dialogo-tra-essere-umano-e-natura-nelle-opere-della-collezione-farnesina\/\" title=\"Identit\u00e0 oltre confine. Dialogo tra essere umano e natura nelle opere della Collezione Farnesina\">Identit\u00e0 oltre confine. Dialogo tra essere umano e natura nelle opere della Collezione Farnesina<\/a><\/h5>\n                            <p class=\"card-text\">A distanza di tre anni dalla mostra La Grande Visione Italiana, organizzata dal Ministero degli Affari Esteri e della Cooperazione Internazionale (MAECI), una nuova selezione di opere della Collezione Farnesina, una delle pi\u00f9 importanti raccolte di arte contemporanea italiana, viene esposta nella cornice Identit\u00e0 oltre confine. Dialogo tra essere umano e natura nelle opere della [&hellip;]<\/p>\n                                <a title=\"Identit\u00e0 oltre confine. Dialogo tra essere umano e natura nelle opere della Collezione Farnesina\" class=\"read-more\" href=\"https:\/\/iictokyo.esteri.it\/it\/gli_eventi\/calendario\/identita-oltre-confine-dialogo-tra-essere-umano-e-natura-nelle-opere-della-collezione-farnesina\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/iictokyo.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                        <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body row\">\n                                                    <div class=\"col-sm-3\">\n                                <div class=\"img-responsive\">\n                                    <figure class=\"img-wrapper\">\n                                        <a href=\"https:\/\/iictokyo.esteri.it\/it\/gli_eventi\/calendario\/identita-oltre-confine-conferenza-di-benedetta-carpi-de-resmini-e-kanai-tadashi\/\" title=\"Leggi l'articolo: Identit\u00e0 oltre confine &#8211; Conferenza di Benedetta Carpi De Resmini e Kanai Tadashi\">\n                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/iictokyo.esteri.it\/wp-content\/uploads\/2026\/08\/Montessori_per_sito-300x169.jpg\" srcset=\"https:\/\/iictokyo.esteri.it\/wp-content\/uploads\/2026\/08\/Montessori_per_sito.jpg 1511w, https:\/\/iictokyo.esteri.it\/wp-content\/uploads\/2026\/08\/Montessori_per_sito-300x169.jpg 300w, https:\/\/iictokyo.esteri.it\/wp-content\/uploads\/2026\/08\/Montessori_per_sito-1024x576.jpg 1024w, https:\/\/iictokyo.esteri.it\/wp-content\/uploads\/2026\/08\/Montessori_per_sito-768x432.jpg 768w\" sizes=\"auto, (max-width: 1511px) 100vw, 1511px\"  title=\"Progetto senza titolo &#8211; 1\" alt=\"Elisa Montessori, Disegni (particolare)\" class=\"img-fluid\">\n                                                                                    <\/a>\n                                    <\/figure>\n                                <\/div>\n                            <\/div>\n                            <div class=\"col-sm-9\">\n                                                            <div class=\"category-top\">\n                                    <span class=\"fw-bold \"><\/span>                                                                        <span class=\"\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/iictokyo.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> Lun 14 Set 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/iictokyo.esteri.it\/it\/gli_eventi\/calendario\/identita-oltre-confine-conferenza-di-benedetta-carpi-de-resmini-e-kanai-tadashi\/\" title=\"Identit\u00e0 oltre confine &#8211; Conferenza di Benedetta Carpi De Resmini e Kanai Tadashi\">Identit\u00e0 oltre confine &#8211; Conferenza di Benedetta Carpi De Resmini e Kanai Tadashi<\/a><\/h5>\n                            <p class=\"card-text\">In occasione della mostra Identit\u00e0 oltre confine. Dialogo tra essere umano e natura nelle opere della Collezione Farnesina la curatrice Benedetta Carpi De Resmini incontra il Prof. Kanai Tadashi, docente della Shinshu University e grande esperto di arte contemporanea italiana. Nella prima parte della serata si spiega come \u00e8 nata l\u2019idea e quali sono le [&hellip;]<\/p>\n                                <a title=\"Identit\u00e0 oltre confine &#8211; Conferenza di Benedetta Carpi De Resmini e Kanai Tadashi\" class=\"read-more\" href=\"https:\/\/iictokyo.esteri.it\/it\/gli_eventi\/calendario\/identita-oltre-confine-conferenza-di-benedetta-carpi-de-resmini-e-kanai-tadashi\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/iictokyo.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                        <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body row\">\n                                                    <div class=\"col-sm-3\">\n                                <div class=\"img-responsive\">\n                                    <figure class=\"img-wrapper\">\n                                        <a href=\"https:\/\/iictokyo.esteri.it\/it\/gli_eventi\/calendario\/concerti-di-tokyo-kudan-minami-n-33-recital-di-alessandro-carbonare-e-kuroda-aki\/\" title=\"Leggi l'articolo: Concerti di Tokyo Kudan Minami n. 33 &#8211; Recital di Alessandro Carbonare e Kuroda Aki\">\n                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"300\" src=\"https:\/\/iictokyo.esteri.it\/wp-content\/uploads\/2026\/08\/Carbonare_Kuroda_per_Sito-240x300.jpg\" srcset=\"https:\/\/iictokyo.esteri.it\/wp-content\/uploads\/2026\/08\/Carbonare_Kuroda_per_Sito.jpg 680w, https:\/\/iictokyo.esteri.it\/wp-content\/uploads\/2026\/08\/Carbonare_Kuroda_per_Sito-240x300.jpg 240w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\"  title=\"Collage foto per sito &#8211; eventi vari &#8211; 2\" alt=\"\" class=\"img-fluid\">\n                                                                                    <\/a>\n                                    <\/figure>\n                                <\/div>\n                            <\/div>\n                            <div class=\"col-sm-9\">\n                                                            <div class=\"category-top\">\n                                    <span class=\"fw-bold \"><\/span>                                                                        <span class=\"\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/iictokyo.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> Mar 15 Set 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/iictokyo.esteri.it\/it\/gli_eventi\/calendario\/concerti-di-tokyo-kudan-minami-n-33-recital-di-alessandro-carbonare-e-kuroda-aki\/\" title=\"Concerti di Tokyo Kudan Minami n. 33 &#8211; Recital di Alessandro Carbonare e Kuroda Aki\">Concerti di Tokyo Kudan Minami n. 33 &#8211; Recital di Alessandro Carbonare e Kuroda Aki<\/a><\/h5>\n                            <p class=\"card-text\">La stagione musicale dell\u2019Istituto, sotto la direzione artistica del Maestro Gaetano D\u2019Espinosa, prosegue con il recital di Alessandro Carbonare, clarinetto, e Aki Kuroda, pianoforte. Il filo immaginario che lega i brani del programma, pi\u00f9 che affinit\u00e0 stilistiche o di genere e prima ancora di un semplice ordine cronologico, \u00e8 il tema del viaggio nella diversit\u00e0. [&hellip;]<\/p>\n                                <a title=\"Concerti di Tokyo Kudan Minami n. 33 &#8211; Recital di Alessandro Carbonare e Kuroda Aki\" class=\"read-more\" href=\"https:\/\/iictokyo.esteri.it\/it\/gli_eventi\/calendario\/concerti-di-tokyo-kudan-minami-n-33-recital-di-alessandro-carbonare-e-kuroda-aki\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/iictokyo.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                        <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body row\">\n                                                    <div class=\"col-sm-3\">\n                                <div class=\"img-responsive\">\n                                    <figure class=\"img-wrapper\">\n                                        <a href=\"https:\/\/iictokyo.esteri.it\/it\/gli_eventi\/calendario\/speech-contest-trentunesima-edizione-finale-e-premiazione\/\" title=\"Leggi l'articolo: Speech contest, trentunesima edizione &#8211; Finale e premiazione\">\n                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/iictokyo.esteri.it\/wp-content\/uploads\/2026\/08\/260923_Foto_per_sito_850-300x200.jpg\" srcset=\"https:\/\/iictokyo.esteri.it\/wp-content\/uploads\/2026\/08\/260923_Foto_per_sito_850.jpg 1275w, https:\/\/iictokyo.esteri.it\/wp-content\/uploads\/2026\/08\/260923_Foto_per_sito_850-300x200.jpg 300w, https:\/\/iictokyo.esteri.it\/wp-content\/uploads\/2026\/08\/260923_Foto_per_sito_850-1024x683.jpg 1024w, https:\/\/iictokyo.esteri.it\/wp-content\/uploads\/2026\/08\/260923_Foto_per_sito_850-768x512.jpg 768w\" sizes=\"auto, (max-width: 1275px) 100vw, 1275px\"  title=\"260923_Foto_per_sito_850\" alt=\"\" class=\"img-fluid\">\n                                                                                    <\/a>\n                                    <\/figure>\n                                <\/div>\n                            <\/div>\n                            <div class=\"col-sm-9\">\n                                                            <div class=\"category-top\">\n                                    <span class=\"fw-bold \"><\/span>                                                                        <span class=\"\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/iictokyo.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> Mer 23 Set 2026<svg class=\"icon icon-xs icon-secondary me-1 ms-1\"><use href=\"https:\/\/iictokyo.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use><\/svg>Mer 23 Set 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/iictokyo.esteri.it\/it\/gli_eventi\/calendario\/speech-contest-trentunesima-edizione-finale-e-premiazione\/\" title=\"Speech contest, trentunesima edizione &#8211; Finale e premiazione\">Speech contest, trentunesima edizione &#8211; Finale e premiazione<\/a><\/h5>\n                            <p class=\"card-text\">Il concorso Speech contest \u00e8 una prova di oratoria in lingua italiana aperta a tutti, senza distinzioni di et\u00e0 o genere, organizzato dall&#8217;Associazione Italo Giapponese con l\u2019obiettivo di promuovere lo studio della lingua italiana. La finale si svolge presso l&#8217;Auditorium dell&#8217;Istituto, che del concorso \u00e8 coorganizzatore. Mercoled\u00ec 23 settembre 2026, dalle ore 13:00 alle ore [&hellip;]<\/p>\n                                <a title=\"Speech contest, trentunesima edizione &#8211; Finale e premiazione\" class=\"read-more\" href=\"https:\/\/iictokyo.esteri.it\/it\/gli_eventi\/calendario\/speech-contest-trentunesima-edizione-finale-e-premiazione\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/iictokyo.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                        <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body row\">\n                                                    <div class=\"col-sm-3\">\n                                <div class=\"img-responsive\">\n                                    <figure class=\"img-wrapper\">\n                                        <a href=\"https:\/\/iictokyo.esteri.it\/it\/gli_eventi\/calendario\/corde-e-martelletti-incontro-con-il-m-o-alessandro-solbiati-ed-i-suoi-allievi\/\" title=\"Leggi l'articolo: Corde e martelletti \u2013 Incontro con il M.o Alessandro Solbiati ed i suoi allievi\">\n                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"249\" src=\"https:\/\/iictokyo.esteri.it\/wp-content\/uploads\/2026\/08\/Solbiati_per_sito-300x249.jpg\" srcset=\"https:\/\/iictokyo.esteri.it\/wp-content\/uploads\/2026\/08\/Solbiati_per_sito.jpg 971w, https:\/\/iictokyo.esteri.it\/wp-content\/uploads\/2026\/08\/Solbiati_per_sito-300x249.jpg 300w, https:\/\/iictokyo.esteri.it\/wp-content\/uploads\/2026\/08\/Solbiati_per_sito-768x637.jpg 768w\" sizes=\"auto, (max-width: 971px) 100vw, 971px\"  title=\"Solbiati_per_sito\" alt=\"\" class=\"img-fluid\">\n                                                                                    <\/a>\n                                    <\/figure>\n                                <\/div>\n                            <\/div>\n                            <div class=\"col-sm-9\">\n                                                            <div class=\"category-top\">\n                                    <span class=\"fw-bold \"><\/span>                                                                        <span class=\"\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/iictokyo.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> Mer 18 Nov 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/iictokyo.esteri.it\/it\/gli_eventi\/calendario\/corde-e-martelletti-incontro-con-il-m-o-alessandro-solbiati-ed-i-suoi-allievi\/\" title=\"Corde e martelletti \u2013 Incontro con il M.o Alessandro Solbiati ed i suoi allievi\">Corde e martelletti \u2013 Incontro con il M.o Alessandro Solbiati ed i suoi allievi<\/a><\/h5>\n                            <p class=\"card-text\">La stagione musicale dell\u2019Istituto, sotto la direzione artistica del Maestro Gaetano D\u2019Espinosa, prosegue con due appuntamenti dedicati ad Alessandro Solbiati: un concerto che si terr\u00e0 venerd\u00ec 20 novembre ed un incontro con il Maestro ed i suoi allievi incentrato su Corde e martelletti. Si tratta di una composizione che consta di cento piccoli pezzi molto [&hellip;]<\/p>\n                                <a title=\"Corde e martelletti \u2013 Incontro con il M.o Alessandro Solbiati ed i suoi allievi\" class=\"read-more\" href=\"https:\/\/iictokyo.esteri.it\/it\/gli_eventi\/calendario\/corde-e-martelletti-incontro-con-il-m-o-alessandro-solbiati-ed-i-suoi-allievi\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/iictokyo.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                        <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body row\">\n                                                    <div class=\"col-sm-3\">\n                                <div class=\"img-responsive\">\n                                    <figure class=\"img-wrapper\">\n                                        <a href=\"https:\/\/iictokyo.esteri.it\/it\/gli_eventi\/calendario\/concerti-di-tokyo-kudan-minami-n-34-concerto-di-musica-da-camera-di-alessandro-solbiati-like-as-the-waves\/\" title=\"Leggi l'articolo: Concerti di Tokyo Kudan Minami n.34 &#8211; Concerto di musica da camera di Alessandro Solbiati Like as the waves\">\n                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"249\" src=\"https:\/\/iictokyo.esteri.it\/wp-content\/uploads\/2026\/08\/Solbiati_per_sito-300x249.jpg\" srcset=\"https:\/\/iictokyo.esteri.it\/wp-content\/uploads\/2026\/08\/Solbiati_per_sito.jpg 971w, https:\/\/iictokyo.esteri.it\/wp-content\/uploads\/2026\/08\/Solbiati_per_sito-300x249.jpg 300w, https:\/\/iictokyo.esteri.it\/wp-content\/uploads\/2026\/08\/Solbiati_per_sito-768x637.jpg 768w\" sizes=\"auto, (max-width: 971px) 100vw, 971px\"  title=\"Solbiati_per_sito\" alt=\"\" class=\"img-fluid\">\n                                                                                    <\/a>\n                                    <\/figure>\n                                <\/div>\n                            <\/div>\n                            <div class=\"col-sm-9\">\n                                                            <div class=\"category-top\">\n                                    <span class=\"fw-bold \"><\/span>                                                                        <span class=\"\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/iictokyo.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> Ven 20 Nov 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/iictokyo.esteri.it\/it\/gli_eventi\/calendario\/concerti-di-tokyo-kudan-minami-n-34-concerto-di-musica-da-camera-di-alessandro-solbiati-like-as-the-waves\/\" title=\"Concerti di Tokyo Kudan Minami n.34 &#8211; Concerto di musica da camera di Alessandro Solbiati Like as the waves\">Concerti di Tokyo Kudan Minami n.34 &#8211; Concerto di musica da camera di Alessandro Solbiati Like as the waves<\/a><\/h5>\n                            <p class=\"card-text\">La stagione musicale dell\u2019Istituto, sotto la direzione artistica del Maestro Gaetano D\u2019Espinosa, prosegue con un concerto di musiche da camera di Alessandro Solbiati. Il concerto ed un incontro dal titolo Corde e martelletti fanno parte di un progetto dedicato al grande compositore dal titolo Alessandro Solbiati in Giappone 2026. Per informazioni sull&#8217;incontro cliccare QUI &nbsp; [&hellip;]<\/p>\n                                <a title=\"Concerti di Tokyo Kudan Minami n.34 &#8211; Concerto di musica da camera di Alessandro Solbiati Like as the waves\" class=\"read-more\" href=\"https:\/\/iictokyo.esteri.it\/it\/gli_eventi\/calendario\/concerti-di-tokyo-kudan-minami-n-34-concerto-di-musica-da-camera-di-alessandro-solbiati-like-as-the-waves\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/iictokyo.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                        <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n            \n            <div class=\"col-md-12 mt-4 pb-4\">\n                <nav class=\"navigation col-md-12\" aria-label=\"Navigation\">\n                    <h2 class=\"screen-reader-text visually-hidden\">Paginazione<\/h2>\n                    <div class=\"nav-links\">\n                                        <\/div>\n                <\/nav>\n            <\/div>   <!--.col-md-12 -->\n              <\/div><!--.row -->\n              \n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":17,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-35","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/iictokyo.esteri.it\/it\/wp-json\/wp\/v2\/pages\/35","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iictokyo.esteri.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/iictokyo.esteri.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/iictokyo.esteri.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/iictokyo.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=35"}],"version-history":[{"count":2,"href":"https:\/\/iictokyo.esteri.it\/it\/wp-json\/wp\/v2\/pages\/35\/revisions"}],"predecessor-version":[{"id":3981,"href":"https:\/\/iictokyo.esteri.it\/it\/wp-json\/wp\/v2\/pages\/35\/revisions\/3981"}],"up":[{"embeddable":true,"href":"https:\/\/iictokyo.esteri.it\/it\/wp-json\/wp\/v2\/pages\/17"}],"wp:attachment":[{"href":"https:\/\/iictokyo.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=35"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}